{"id":542,"count":6,"description":"","link":"https:\/\/blog.flipbuilder.com\/nl\/category\/magazine\/magazine-design-idea\/","name":"Idee voor tijdschriftontwerp","slug":"magazine-design-idea","taxonomy":"category","parent":379,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Magazine Design Idea Archives - FlipBuilder Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.flipbuilder.com\/nl\/category\/magazine\/magazine-design-idea\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Magazine Design Idea Archives - FlipBuilder Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.flipbuilder.com\/nl\/category\/magazine\/magazine-design-idea\/\" \/>\n<meta property=\"og:site_name\" content=\"FlipBuilder Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.flipbuilder.com\/category\/magazine\/magazine-design-idea\/\",\"url\":\"https:\/\/blog.flipbuilder.com\/category\/magazine\/magazine-design-idea\/\",\"name\":\"Magazine Design Idea Archives - FlipBuilder Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.flipbuilder.com\/tr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.flipbuilder.com\/category\/magazine\/magazine-design-idea\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.flipbuilder.com\/category\/magazine\/magazine-design-idea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.flipbuilder.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magazine\",\"item\":\"https:\/\/blog.flipbuilder.com\/hu\/category\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Magazine Design Idea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.flipbuilder.com\/tr\/#website\",\"url\":\"https:\/\/blog.flipbuilder.com\/tr\/\",\"name\":\"FlipBuilder Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/blog.flipbuilder.com\/tr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.flipbuilder.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.flipbuilder.com\/tr\/#organization\",\"name\":\"FlipBuilder Blog\",\"url\":\"https:\/\/blog.flipbuilder.com\/tr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/blog.flipbuilder.com\/tr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.flipbuilder.com\/wp-content\/uploads\/2022\/07\/logo-2-1-1.png\",\"contentUrl\":\"https:\/\/blog.flipbuilder.com\/wp-content\/uploads\/2022\/07\/logo-2-1-1.png\",\"width\":190,\"height\":38,\"caption\":\"FlipBuilder Blog\"},\"image\":{\"@id\":\"https:\/\/blog.flipbuilder.com\/tr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Magazine Design Idea Archives - FlipBuilder Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.flipbuilder.com\/nl\/category\/magazine\/magazine-design-idea\/","og_locale":"nl_NL","og_type":"article","og_title":"Magazine Design Idea Archives - FlipBuilder Blog","og_url":"https:\/\/blog.flipbuilder.com\/nl\/category\/magazine\/magazine-design-idea\/","og_site_name":"FlipBuilder Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.flipbuilder.com\/category\/magazine\/magazine-design-idea\/","url":"https:\/\/blog.flipbuilder.com\/category\/magazine\/magazine-design-idea\/","name":"Magazine Design Idea Archives - FlipBuilder Blog","isPartOf":{"@id":"https:\/\/blog.flipbuilder.com\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/blog.flipbuilder.com\/category\/magazine\/magazine-design-idea\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.flipbuilder.com\/category\/magazine\/magazine-design-idea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.flipbuilder.com\/"},{"@type":"ListItem","position":2,"name":"Magazine","item":"https:\/\/blog.flipbuilder.com\/hu\/category\/magazine\/"},{"@type":"ListItem","position":3,"name":"Magazine Design Idea"}]},{"@type":"WebSite","@id":"https:\/\/blog.flipbuilder.com\/tr\/#website","url":"https:\/\/blog.flipbuilder.com\/tr\/","name":"FlipBuilder Blog","description":"","publisher":{"@id":"https:\/\/blog.flipbuilder.com\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.flipbuilder.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/blog.flipbuilder.com\/tr\/#organization","name":"FlipBuilder Blog","url":"https:\/\/blog.flipbuilder.com\/tr\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/blog.flipbuilder.com\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.flipbuilder.com\/wp-content\/uploads\/2022\/07\/logo-2-1-1.png","contentUrl":"https:\/\/blog.flipbuilder.com\/wp-content\/uploads\/2022\/07\/logo-2-1-1.png","width":190,"height":38,"caption":"FlipBuilder Blog"},"image":{"@id":"https:\/\/blog.flipbuilder.com\/tr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.flipbuilder.com\/nl\/wp-json\/wp\/v2\/categories\/542"}],"collection":[{"href":"https:\/\/blog.flipbuilder.com\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.flipbuilder.com\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blog.flipbuilder.com\/nl\/wp-json\/wp\/v2\/categories\/379"}],"wp:post_type":[{"href":"https:\/\/blog.flipbuilder.com\/nl\/wp-json\/wp\/v2\/posts?categories=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}